{"id":10230,"date":"2021-10-03T08:50:08","date_gmt":"2021-10-03T11:50:08","guid":{"rendered":"http:\/\/www.portalmiradouro.com.br\/site\/?p=10230"},"modified":"2021-10-04T12:15:09","modified_gmt":"2021-10-04T15:15:09","slug":"onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos","status":"publish","type":"post","link":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/","title":{"rendered":"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos."},"content":{"rendered":"<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-cai-em-ribanceira-em-leopoldina-e-deixa-mortos-e-feridos-na-madrugada-deste-domingo\/3067779945a39497cdf64ffc06616683-6editada-7\/\" rel=\"attachment wp-att-10242\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10242\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg\" alt=\"\" width=\"700\" height=\"525\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Fotos da R\u00e1dio Muria\u00e9, parceira do Portal Miradouro<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-cai-em-ribanceira-em-leopoldina-e-deixa-mortos-e-feridos-na-madrugada-deste-domingo\/ae92fe7bcb8fdd1a07d05d2ffb10c44b-11editada-12\/\" rel=\"attachment wp-att-10243\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10243\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/ae92fe7bcb8fdd1a07d05d2ffb10c44b.11editada-12.jpg\" alt=\"\" width=\"700\" height=\"525\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-cai-em-ribanceira-em-leopoldina-e-deixa-mortos-e-feridos-na-madrugada-deste-domingo\/8da487c4e5e88b5979ede7b15e512d70-12editada-13\/\" rel=\"attachment wp-att-10240\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10240\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/8da487c4e5e88b5979ede7b15e512d70.12editada-13.jpg\" alt=\"\" width=\"700\" height=\"525\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Um \u00f4nibus da empresa Gontijo, caiu em uma ribanceira de aproximadamente 80 metros, na Serra da Vileta, em Leopoldina. De acordo com a PRF, o acidente aconteceu por volta das 23h30, quando o \u00f4nibus que teria sa\u00eddo do munic\u00edpio de Barra do Rocha, em S\u00e3o Paulo com destino \u00e0 cidade de Ubat\u00e3, na Bahia, no ve\u00edculo viajavam 52 pessoas, sendo 44 adultos e cinco crian\u00e7as. Com a gravidade do acidente v\u00e1rias equipes do Corpo de Bombeiros de Leopoldina, Al\u00e9m Para\u00edba, Juiz de Fora e equipes do SAMU de toda regi\u00e3o, al\u00e9m da Pol\u00edcia Rodovi\u00e1ria Federal e Pol\u00edcia Militar. O \u00f4nibus ficou submerso, apenas com as rodas fora da \u00e1gua, at\u00e9 o momento foram registrados, 4 mortos e 44 feridos.<\/span><\/p>\n<p><em><strong><span style=\"color: #000000;\">Informa\u00e7\u00f5es da Pol\u00edcia Civil de Minas Gerais sobre o tr\u00e1gico acidente em Leopoldina:<\/span><\/strong><\/em><\/p>\n<p><span style=\"color: #000000;\">Sobre o caso registrado como acidente de tr\u00e2nsito com v\u00edtimas, Dr. Rafael Spork da Costa, respons\u00e1vel pela apura\u00e7\u00e3o, informou que um inqu\u00e9rito policial foi instaurado para apurar as circunst\u00e2ncias do acidente, exames periciais m\u00e9dicos j\u00e1 foram requisitados, toxicol\u00f3gicos e alcoolemia do motorista tamb\u00e9m, a necropsia das v\u00edtimas j\u00e1 foram realizadas e as quatro v\u00edtimas foram identificadas. Foi feita per\u00edcia no local e dilig\u00eancias foram realizadas. As investiga\u00e7\u00f5es prosseguem no sentido de apurar as circunst\u00e2ncias deste acidente.<\/span><\/p>\n<p><span style=\"color: #000000;\">Daqui a pouco mais informa\u00e7\u00f5es.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotos da R\u00e1dio Muria\u00e9, parceira do Portal Miradouro &nbsp; Um \u00f4nibus da empresa Gontijo, caiu em uma ribanceira de aproximadamente 80 metros, na Serra da Vileta, em Leopoldina. De acordo com a PRF, o acidente aconteceu por volta das 23h30, quando o \u00f4nibus que teria sa\u00eddo do munic\u00edpio de Barra do Rocha, em S\u00e3o Paulo com destino \u00e0 cidade de Ubat\u00e3, na Bahia, no ve\u00edculo viajavam 52 pessoas, sendo 44 adultos e cinco crian\u00e7as. Com a gravidade do acidente v\u00e1rias equipes do Corpo de Bombeiros de Leopoldina, Al\u00e9m Para\u00edba, Juiz de Fora e equipes do SAMU de toda regi\u00e3o, al\u00e9m da Pol\u00edcia Rodovi\u00e1ria Federal e Pol\u00edcia Militar. O \u00f4nibus ficou submerso, apenas com as rodas fora da \u00e1gua, at\u00e9 o momento foram registrados, 4 mortos e 44 feridos. Informa\u00e7\u00f5es da Pol\u00edcia Civil de Minas Gerais sobre o tr\u00e1gico acidente em Leopoldina: Sobre o caso registrado como acidente de tr\u00e2nsito com v\u00edtimas, Dr. Rafael Spork da Costa, respons\u00e1vel pela apura\u00e7\u00e3o, informou que um inqu\u00e9rito policial foi instaurado para apurar as circunst\u00e2ncias do acidente, exames periciais m\u00e9dicos j\u00e1 foram requisitados, toxicol\u00f3gicos e alcoolemia do motorista tamb\u00e9m, a necropsia das v\u00edtimas j\u00e1 foram realizadas e as quatro v\u00edtimas foram identificadas. Foi feita per\u00edcia no local e dilig\u00eancias foram realizadas. As investiga\u00e7\u00f5es prosseguem no sentido de apurar as circunst\u00e2ncias deste acidente. Daqui a pouco mais informa\u00e7\u00f5es.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"categories":[1060,1],"tags":[143,1381,1530,458,317,145],"author_meta":{"display_name":"Portal Miradouro","author_link":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"},"featured_img":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro\" \/>\n<meta property=\"og:description\" content=\"Fotos da R\u00e1dio Muria\u00e9, parceira do Portal Miradouro &nbsp; Um \u00f4nibus da empresa Gontijo, caiu em uma ribanceira de aproximadamente 80 metros, na Serra da Vileta, em Leopoldina. De acordo com a PRF, o acidente aconteceu por volta das 23h30, quando o \u00f4nibus que teria sa\u00eddo do munic\u00edpio de Barra do Rocha, em S\u00e3o Paulo com destino \u00e0 cidade de Ubat\u00e3, na Bahia, no ve\u00edculo viajavam 52 pessoas, sendo 44 adultos e cinco crian\u00e7as. Com a gravidade do acidente v\u00e1rias equipes do Corpo de Bombeiros de Leopoldina, Al\u00e9m Para\u00edba, Juiz de Fora e equipes do SAMU de toda regi\u00e3o, al\u00e9m da Pol\u00edcia Rodovi\u00e1ria Federal e Pol\u00edcia Militar. O \u00f4nibus ficou submerso, apenas com as rodas fora da \u00e1gua, at\u00e9 o momento foram registrados, 4 mortos e 44 feridos. Informa\u00e7\u00f5es da Pol\u00edcia Civil de Minas Gerais sobre o tr\u00e1gico acidente em Leopoldina: Sobre o caso registrado como acidente de tr\u00e2nsito com v\u00edtimas, Dr. Rafael Spork da Costa, respons\u00e1vel pela apura\u00e7\u00e3o, informou que um inqu\u00e9rito policial foi instaurado para apurar as circunst\u00e2ncias do acidente, exames periciais m\u00e9dicos j\u00e1 foram requisitados, toxicol\u00f3gicos e alcoolemia do motorista tamb\u00e9m, a necropsia das v\u00edtimas j\u00e1 foram realizadas e as quatro v\u00edtimas foram identificadas. Foi feita per\u00edcia no local e dilig\u00eancias foram realizadas. As investiga\u00e7\u00f5es prosseguem no sentido de apurar as circunst\u00e2ncias deste acidente. Daqui a pouco mais informa\u00e7\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Miradouro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalmiradouro2020\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-03T11:50:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-04T15:15:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Miradouro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/\",\"name\":\"Portal Miradouro\",\"description\":\"O seu portal de not\\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg\",\"contentUrl\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#webpage\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/\",\"name\":\"\\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro\",\"isPartOf\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#primaryimage\"},\"datePublished\":\"2021-10-03T11:50:08+00:00\",\"dateModified\":\"2021-10-04T15:15:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.portalmiradouro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos.\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\",\"name\":\"Portal Miradouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"caption\":\"Portal Miradouro\"},\"sameAs\":[\"http:\/\/www.portalmiradouro.com.br\",\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\",\"https:\/\/www.instagram.com\/portalmiradouro\/\",\"https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/\",\"https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w\"],\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro","og_description":"Fotos da R\u00e1dio Muria\u00e9, parceira do Portal Miradouro &nbsp; Um \u00f4nibus da empresa Gontijo, caiu em uma ribanceira de aproximadamente 80 metros, na Serra da Vileta, em Leopoldina. De acordo com a PRF, o acidente aconteceu por volta das 23h30, quando o \u00f4nibus que teria sa\u00eddo do munic\u00edpio de Barra do Rocha, em S\u00e3o Paulo com destino \u00e0 cidade de Ubat\u00e3, na Bahia, no ve\u00edculo viajavam 52 pessoas, sendo 44 adultos e cinco crian\u00e7as. Com a gravidade do acidente v\u00e1rias equipes do Corpo de Bombeiros de Leopoldina, Al\u00e9m Para\u00edba, Juiz de Fora e equipes do SAMU de toda regi\u00e3o, al\u00e9m da Pol\u00edcia Rodovi\u00e1ria Federal e Pol\u00edcia Militar. O \u00f4nibus ficou submerso, apenas com as rodas fora da \u00e1gua, at\u00e9 o momento foram registrados, 4 mortos e 44 feridos. Informa\u00e7\u00f5es da Pol\u00edcia Civil de Minas Gerais sobre o tr\u00e1gico acidente em Leopoldina: Sobre o caso registrado como acidente de tr\u00e2nsito com v\u00edtimas, Dr. Rafael Spork da Costa, respons\u00e1vel pela apura\u00e7\u00e3o, informou que um inqu\u00e9rito policial foi instaurado para apurar as circunst\u00e2ncias do acidente, exames periciais m\u00e9dicos j\u00e1 foram requisitados, toxicol\u00f3gicos e alcoolemia do motorista tamb\u00e9m, a necropsia das v\u00edtimas j\u00e1 foram realizadas e as quatro v\u00edtimas foram identificadas. Foi feita per\u00edcia no local e dilig\u00eancias foram realizadas. As investiga\u00e7\u00f5es prosseguem no sentido de apurar as circunst\u00e2ncias deste acidente. Daqui a pouco mais informa\u00e7\u00f5es.","og_url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/","og_site_name":"Portal Miradouro","article_publisher":"https:\/\/www.facebook.com\/portalmiradouro2020","article_author":"https:\/\/www.facebook.com\/Portalmiradouro.com.br","article_published_time":"2021-10-03T11:50:08+00:00","article_modified_time":"2021-10-04T15:15:09+00:00","og_image":[{"url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Portal Miradouro","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website","url":"https:\/\/www.portalmiradouro.com.br\/site\/","name":"Portal Miradouro","description":"O seu portal de not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg","contentUrl":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/10\/3067779945a39497cdf64ffc06616683.6editada-7.jpg"},{"@type":"WebPage","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#webpage","url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/","name":"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos. - Portal Miradouro","isPartOf":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#primaryimage"},"datePublished":"2021-10-03T11:50:08+00:00","dateModified":"2021-10-04T15:15:09+00:00","author":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6"},"breadcrumb":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/10\/03\/onibus-da-empresa-gontijo-em-ribanceira-na-serra-da-vileta-em-leopoldina-e-deixa-4-mortos-e-masi-de-40-feridos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portalmiradouro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"\u00d4nibus da empresa Gontijo cai em ribanceira na Serra da Vileta em Leopoldina e deixa 4 mortos e mais de 40 feridos."}]},{"@type":"Person","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6","name":"Portal Miradouro","image":{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","caption":"Portal Miradouro"},"sameAs":["http:\/\/www.portalmiradouro.com.br","https:\/\/www.facebook.com\/Portalmiradouro.com.br","https:\/\/www.instagram.com\/portalmiradouro\/","https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/","https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w"],"url":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/acidentes\/\" class=\"advgb-post-tax-term\">ACIDENTES<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Destaque<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ACIDENTES<\/span>","<span class=\"advgb-post-tax-term\">Destaque<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Acidente<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Bahia<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Gontijo<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">leopoldina<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">\u00f4nibus<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">PRF<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Acidente<\/span>","<span class=\"advgb-post-tax-term\">Bahia<\/span>","<span class=\"advgb-post-tax-term\">Gontijo<\/span>","<span class=\"advgb-post-tax-term\">leopoldina<\/span>","<span class=\"advgb-post-tax-term\">\u00f4nibus<\/span>","<span class=\"advgb-post-tax-term\">PRF<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 5 anos ago","modified":"Updated 5 anos ago"},"absolute_dates":{"created":"Posted on 3 de outubro de 2021","modified":"Updated on 4 de outubro de 2021"},"absolute_dates_time":{"created":"Posted on 3 de outubro de 2021 08:50","modified":"Updated on 4 de outubro de 2021 12:15"},"featured_img_caption":"","_links":{"self":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/10230"}],"collection":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/comments?post=10230"}],"version-history":[{"count":8,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/10230\/revisions"}],"predecessor-version":[{"id":10303,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/10230\/revisions\/10303"}],"wp:attachment":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/media?parent=10230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/categories?post=10230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/tags?post=10230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}