{"id":11988,"date":"2021-12-10T13:46:28","date_gmt":"2021-12-10T16:46:28","guid":{"rendered":"http:\/\/www.portalmiradouro.com.br\/site\/?p=11988"},"modified":"2021-12-10T13:46:29","modified_gmt":"2021-12-10T16:46:29","slug":"tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae","status":"publish","type":"post","link":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/","title":{"rendered":"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9"},"content":{"rendered":"<p><span style=\"color: #000000;\">A Pol\u00edcia Rodovi\u00e1ria Federal de Muria\u00e9 foi acionada por volta das 03h10 da madrugada desta quarta-feira e as informa\u00e7\u00f5es davam conta de que teria um homem ca\u00eddo pr\u00f3ximo a ponte entre o Trevo do Porto e a AABB.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/moto\/\" rel=\"attachment wp-att-11989\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-11989\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg\" alt=\"\" width=\"304\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Fotos e informa\u00e7\u00f5es do site Silvan Alves nosso parceiro em Muria\u00e9<\/span><\/p>\n<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/moto2-768x567\/\" rel=\"attachment wp-att-11990\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-11990\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto2-768x567-1.jpg\" alt=\"\" width=\"714\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\n<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/moto3-768x564\/\" rel=\"attachment wp-att-11991\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-11991\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto3-768x564-1.jpg\" alt=\"\" width=\"718\" height=\"527\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Uma testemunha, taxista havia passado pelo local e visto o homem ca\u00eddo e acionado primeiro a PM, que o verificar, viu que a v\u00edtima estava sem vida. Em vistoria pelo local, as autoridades constataram que se tratava de um acidente, pois uma motocicleta estava dentro do c\u00f3rrego, e teria batido na lateral de prote\u00e7\u00e3o da ponte quando transitava no sentido Barra. O Corpo de Bombeiros e o SAMU tamb\u00e9m foram para o local realizando todos os procedimentos com rela\u00e7\u00e3o \u00e0 v\u00edtima. A v\u00edtima fatal foi identificada como Felipe Costa Moura Cunha, 26 anos de idade, e o fato foi comunicado posteriormente aos familiares. A Per\u00edcia T\u00e9cnica foi acionada, fez os trabalhos no local liberou o corpo para o IML.<\/span><\/p>\n<p><span style=\"color: #000000;\">Fonte: Silvan Alves nosso parceiro em Muria\u00e9<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Federal de Muria\u00e9 foi acionada por volta das 03h10 da madrugada desta quarta-feira e as informa\u00e7\u00f5es davam conta de que teria um homem ca\u00eddo pr\u00f3ximo a ponte entre o Trevo do Porto e a AABB. &nbsp; Fotos e informa\u00e7\u00f5es do site Silvan Alves nosso parceiro em Muria\u00e9 &nbsp; Uma testemunha, taxista havia passado pelo local e visto o homem ca\u00eddo e acionado primeiro a PM, que o verificar, viu que a v\u00edtima estava sem vida. Em vistoria pelo local, as autoridades constataram que se tratava de um acidente, pois uma motocicleta estava dentro do c\u00f3rrego, e teria batido na lateral de prote\u00e7\u00e3o da ponte quando transitava no sentido Barra. O Corpo de Bombeiros e o SAMU tamb\u00e9m foram para o local realizando todos os procedimentos com rela\u00e7\u00e3o \u00e0 v\u00edtima. A v\u00edtima fatal foi identificada como Felipe Costa Moura Cunha, 26 anos de idade, e o fato foi comunicado posteriormente aos familiares. A Per\u00edcia T\u00e9cnica foi acionada, fez os trabalhos no local liberou o corpo para o IML. Fonte: Silvan Alves nosso parceiro em Muria\u00e9<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"categories":[1060,1],"tags":[143,1366,487,1671],"author_meta":{"display_name":"Portal Miradouro","author_link":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"},"featured_img":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9 - Portal Miradouro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9 - Portal Miradouro\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Rodovi\u00e1ria Federal de Muria\u00e9 foi acionada por volta das 03h10 da madrugada desta quarta-feira e as informa\u00e7\u00f5es davam conta de que teria um homem ca\u00eddo pr\u00f3ximo a ponte entre o Trevo do Porto e a AABB. &nbsp; Fotos e informa\u00e7\u00f5es do site Silvan Alves nosso parceiro em Muria\u00e9 &nbsp; Uma testemunha, taxista havia passado pelo local e visto o homem ca\u00eddo e acionado primeiro a PM, que o verificar, viu que a v\u00edtima estava sem vida. Em vistoria pelo local, as autoridades constataram que se tratava de um acidente, pois uma motocicleta estava dentro do c\u00f3rrego, e teria batido na lateral de prote\u00e7\u00e3o da ponte quando transitava no sentido Barra. O Corpo de Bombeiros e o SAMU tamb\u00e9m foram para o local realizando todos os procedimentos com rela\u00e7\u00e3o \u00e0 v\u00edtima. A v\u00edtima fatal foi identificada como Felipe Costa Moura Cunha, 26 anos de idade, e o fato foi comunicado posteriormente aos familiares. A Per\u00edcia T\u00e9cnica foi acionada, fez os trabalhos no local liberou o corpo para o IML. Fonte: Silvan Alves nosso parceiro em Muria\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Miradouro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalmiradouro2020\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T16:46:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-10T16:46:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Miradouro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/\",\"name\":\"Portal Miradouro\",\"description\":\"O seu portal de not\\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg\",\"contentUrl\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#webpage\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/\",\"name\":\"Tr\\u00e1gico acidente na BR 356, pr\\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\\u00e9 - Portal Miradouro\",\"isPartOf\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#primaryimage\"},\"datePublished\":\"2021-12-10T16:46:28+00:00\",\"dateModified\":\"2021-12-10T16:46:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.portalmiradouro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\\u00e1gico acidente na BR 356, pr\\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\\u00e9\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\",\"name\":\"Portal Miradouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"caption\":\"Portal Miradouro\"},\"sameAs\":[\"http:\/\/www.portalmiradouro.com.br\",\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\",\"https:\/\/www.instagram.com\/portalmiradouro\/\",\"https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/\",\"https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w\"],\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9 - Portal Miradouro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/","og_locale":"pt_BR","og_type":"article","og_title":"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9 - Portal Miradouro","og_description":"A Pol\u00edcia Rodovi\u00e1ria Federal de Muria\u00e9 foi acionada por volta das 03h10 da madrugada desta quarta-feira e as informa\u00e7\u00f5es davam conta de que teria um homem ca\u00eddo pr\u00f3ximo a ponte entre o Trevo do Porto e a AABB. &nbsp; Fotos e informa\u00e7\u00f5es do site Silvan Alves nosso parceiro em Muria\u00e9 &nbsp; Uma testemunha, taxista havia passado pelo local e visto o homem ca\u00eddo e acionado primeiro a PM, que o verificar, viu que a v\u00edtima estava sem vida. Em vistoria pelo local, as autoridades constataram que se tratava de um acidente, pois uma motocicleta estava dentro do c\u00f3rrego, e teria batido na lateral de prote\u00e7\u00e3o da ponte quando transitava no sentido Barra. O Corpo de Bombeiros e o SAMU tamb\u00e9m foram para o local realizando todos os procedimentos com rela\u00e7\u00e3o \u00e0 v\u00edtima. A v\u00edtima fatal foi identificada como Felipe Costa Moura Cunha, 26 anos de idade, e o fato foi comunicado posteriormente aos familiares. A Per\u00edcia T\u00e9cnica foi acionada, fez os trabalhos no local liberou o corpo para o IML. Fonte: Silvan Alves nosso parceiro em Muria\u00e9","og_url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/","og_site_name":"Portal Miradouro","article_publisher":"https:\/\/www.facebook.com\/portalmiradouro2020","article_author":"https:\/\/www.facebook.com\/Portalmiradouro.com.br","article_published_time":"2021-12-10T16:46:28+00:00","article_modified_time":"2021-12-10T16:46:29+00:00","og_image":[{"url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Portal Miradouro","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website","url":"https:\/\/www.portalmiradouro.com.br\/site\/","name":"Portal Miradouro","description":"O seu portal de not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg","contentUrl":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/12\/moto.jpg"},{"@type":"WebPage","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#webpage","url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/","name":"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9 - Portal Miradouro","isPartOf":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#primaryimage"},"datePublished":"2021-12-10T16:46:28+00:00","dateModified":"2021-12-10T16:46:29+00:00","author":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6"},"breadcrumb":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/12\/10\/tragico-acidente-na-br-356-proximo-da-aabb-na-madrugada-desta-sexta-feira-10-12-em-muriae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portalmiradouro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1gico acidente na BR 356, pr\u00f3ximo da AABB na madrugada desta sexta-feira (10-12) em Muria\u00e9"}]},{"@type":"Person","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6","name":"Portal Miradouro","image":{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","caption":"Portal Miradouro"},"sameAs":["http:\/\/www.portalmiradouro.com.br","https:\/\/www.facebook.com\/Portalmiradouro.com.br","https:\/\/www.instagram.com\/portalmiradouro\/","https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/","https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w"],"url":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/acidentes\/\" class=\"advgb-post-tax-term\">ACIDENTES<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Destaque<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ACIDENTES<\/span>","<span class=\"advgb-post-tax-term\">Destaque<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Acidente<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">BR 356<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">moto<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Tr\u00e1gico<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Acidente<\/span>","<span class=\"advgb-post-tax-term\">BR 356<\/span>","<span class=\"advgb-post-tax-term\">moto<\/span>","<span class=\"advgb-post-tax-term\">Tr\u00e1gico<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 4 anos ago","modified":"Updated 4 anos ago"},"absolute_dates":{"created":"Posted on 10 de dezembro de 2021","modified":"Updated on 10 de dezembro de 2021"},"absolute_dates_time":{"created":"Posted on 10 de dezembro de 2021 13:46","modified":"Updated on 10 de dezembro de 2021 13:46"},"featured_img_caption":"","_links":{"self":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/11988"}],"collection":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/comments?post=11988"}],"version-history":[{"count":2,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/11988\/revisions"}],"predecessor-version":[{"id":11993,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/11988\/revisions\/11993"}],"wp:attachment":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/media?parent=11988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/categories?post=11988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/tags?post=11988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}