{"id":13060,"date":"2022-01-16T20:38:04","date_gmt":"2022-01-16T23:38:04","guid":{"rendered":"http:\/\/www.portalmiradouro.com.br\/site\/?p=13060"},"modified":"2022-01-16T21:38:11","modified_gmt":"2022-01-17T00:38:11","slug":"grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01","status":"publish","type":"post","link":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/","title":{"rendered":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)"},"content":{"rendered":"<p><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/02-245\/\" rel=\"attachment wp-att-13062\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-13062\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/02-8.jpeg\" alt=\"\" width=\"703\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Fotos: M\u00e1rcio Prado, rep\u00f3rter do Portal 675 &#8211; Fervedouro Not\u00edcias<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/03-203\/\" rel=\"attachment wp-att-13063\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-13063\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/03-5.jpeg\" alt=\"\" width=\"703\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/05-131\/\" rel=\"attachment wp-att-13065\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-13065\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/05-2.jpeg\" alt=\"\" width=\"703\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/01-257\/\" rel=\"attachment wp-att-13061\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-13061\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/01-5.jpeg\" alt=\"\" width=\"703\" height=\"527\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/07-77\/\" rel=\"attachment wp-att-13067\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-13067\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/07.jpeg\" alt=\"\" width=\"703\" height=\"527\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\">Um grave acidente foi registrado na tarde deste domingo (16-01) na BR 482, na regi\u00e3o da Serra da Batata, entre Fervedouro e Carangola.<\/span><\/p>\n<p><span style=\"color: #000000;\">Segundo as informa\u00e7\u00f5es apuradas no local pelo rep\u00f3rter M\u00e1rcio Prado do Portal 675 \u2013 Fervedouro Not\u00edcias, a colis\u00e3o aconteceu por 14 horas, envolvendo dois ve\u00edculos, os condutores foram socorridos pelo SAMU de Fervedouro e encaminhados para o Hospital Santa B\u00e1rbara em Fervedouro em seguida levados para o Hospital de Carangola. Ainda segundo informa\u00e7\u00f5es do rep\u00f3rter M\u00e1rcio Prado, um dos condutores teria fraturado uma das pernas.<\/span><\/p>\n<p><span style=\"color: #000000;\">O tr\u00e2nsito foi controlado pelo Pol\u00edcia Militar de Fervedouro at\u00e9 a chegada da Pol\u00edcia Militar Estadual de Carangola, que assumiu a ocorr\u00eancia.<\/span><\/p>\n<p style=\"text-align: center;\"><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/igfwKo4T_uk\" width=\"720\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p><span style=\"color: #000000;\">Fonte: Portal Miradouro \u2013 Informa\u00e7\u00f5es e Fotos do Portal 675 \u2013 Fervedouro Not\u00edcias<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotos: M\u00e1rcio Prado, rep\u00f3rter do Portal 675 &#8211; Fervedouro Not\u00edcias Um grave acidente foi registrado na tarde deste domingo (16-01) na BR 482, na regi\u00e3o da Serra da Batata, entre Fervedouro e Carangola. Segundo as informa\u00e7\u00f5es apuradas no local pelo rep\u00f3rter M\u00e1rcio Prado do Portal 675 \u2013 Fervedouro Not\u00edcias, a colis\u00e3o aconteceu por 14 horas, envolvendo dois ve\u00edculos, os condutores foram socorridos pelo SAMU de Fervedouro e encaminhados para o Hospital Santa B\u00e1rbara em Fervedouro em seguida levados para o Hospital de Carangola. Ainda segundo informa\u00e7\u00f5es do rep\u00f3rter M\u00e1rcio Prado, um dos condutores teria fraturado uma das pernas. O tr\u00e2nsito foi controlado pelo Pol\u00edcia Militar de Fervedouro at\u00e9 a chegada da Pol\u00edcia Militar Estadual de Carangola, que assumiu a ocorr\u00eancia. \ufeff\ufeff Fonte: Portal Miradouro \u2013 Informa\u00e7\u00f5es e Fotos do Portal 675 \u2013 Fervedouro Not\u00edcias<\/p>\n","protected":false},"author":2,"featured_media":13068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"categories":[1060,1,9,5],"tags":[143,136,1775],"author_meta":{"display_name":"Portal Miradouro","author_link":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"},"featured_img":"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa-300x224.jpeg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro<\/title>\n<meta name=\"description\" content=\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro\" \/>\n<meta property=\"og:description\" content=\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Miradouro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalmiradouro2020\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-16T23:38:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T00:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"706\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Miradouro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/\",\"name\":\"Portal Miradouro\",\"description\":\"O seu portal de not\\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg\",\"contentUrl\":\"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg\",\"width\":706,\"height\":527},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#webpage\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/\",\"name\":\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro\",\"isPartOf\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#primaryimage\"},\"datePublished\":\"2022-01-16T23:38:04+00:00\",\"dateModified\":\"2022-01-17T00:38:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\"},\"description\":\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)\",\"breadcrumb\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.portalmiradouro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\",\"name\":\"Portal Miradouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"caption\":\"Portal Miradouro\"},\"sameAs\":[\"http:\/\/www.portalmiradouro.com.br\",\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\",\"https:\/\/www.instagram.com\/portalmiradouro\/\",\"https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/\",\"https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w\"],\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro","description":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/","og_locale":"pt_BR","og_type":"article","og_title":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro","og_description":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)","og_url":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/","og_site_name":"Portal Miradouro","article_publisher":"https:\/\/www.facebook.com\/portalmiradouro2020","article_author":"https:\/\/www.facebook.com\/Portalmiradouro.com.br","article_published_time":"2022-01-16T23:38:04+00:00","article_modified_time":"2022-01-17T00:38:11+00:00","og_image":[{"width":706,"height":527,"url":"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Portal Miradouro","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website","url":"https:\/\/www.portalmiradouro.com.br\/site\/","name":"Portal Miradouro","description":"O seu portal de not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg","contentUrl":"https:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2022\/01\/capa.jpeg","width":706,"height":527},{"@type":"WebPage","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#webpage","url":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/","name":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01) - Portal Miradouro","isPartOf":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#primaryimage"},"datePublished":"2022-01-16T23:38:04+00:00","dateModified":"2022-01-17T00:38:11+00:00","author":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6"},"description":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)","breadcrumb":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2022\/01\/16\/grave-acidente-na-serra-da-batata-em-fervedouro-deixa-duas-pessoas-feridas-na-tarde-deste-domingo-16-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portalmiradouro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Grave acidente na Serra da Batata em Fervedouro deixa duas pessoas feridas na tarde deste domingo (16-01)"}]},{"@type":"Person","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6","name":"Portal Miradouro","image":{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","caption":"Portal Miradouro"},"sameAs":["http:\/\/www.portalmiradouro.com.br","https:\/\/www.facebook.com\/Portalmiradouro.com.br","https:\/\/www.instagram.com\/portalmiradouro\/","https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/","https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w"],"url":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/acidentes\/\" class=\"advgb-post-tax-term\">ACIDENTES<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Destaque<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/noticias-lateral\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal-principal\/\" class=\"advgb-post-tax-term\">Portal Miradouro<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ACIDENTES<\/span>","<span class=\"advgb-post-tax-term\">Destaque<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>","<span class=\"advgb-post-tax-term\">Portal Miradouro<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal-principal\/\" class=\"advgb-post-tax-term\">Acidente<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal-principal\/\" class=\"advgb-post-tax-term\">Fervedouro<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal-principal\/\" class=\"advgb-post-tax-term\">Serra da Batata<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Acidente<\/span>","<span class=\"advgb-post-tax-term\">Fervedouro<\/span>","<span class=\"advgb-post-tax-term\">Serra da Batata<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 4 anos ago","modified":"Updated 4 anos ago"},"absolute_dates":{"created":"Posted on 16 de janeiro de 2022","modified":"Updated on 16 de janeiro de 2022"},"absolute_dates_time":{"created":"Posted on 16 de janeiro de 2022 20:38","modified":"Updated on 16 de janeiro de 2022 21:38"},"featured_img_caption":"","_links":{"self":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/13060"}],"collection":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/comments?post=13060"}],"version-history":[{"count":7,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/13060\/revisions"}],"predecessor-version":[{"id":13075,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/13060\/revisions\/13075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/media\/13068"}],"wp:attachment":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/media?parent=13060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/categories?post=13060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/tags?post=13060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}