{"id":2099,"date":"2021-01-29T17:57:32","date_gmt":"2021-01-29T20:57:32","guid":{"rendered":"http:\/\/www.portalmiradouro.com.br\/site\/?p=2099"},"modified":"2021-01-29T17:57:32","modified_gmt":"2021-01-29T20:57:32","slug":"miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2","status":"publish","type":"post","link":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/","title":{"rendered":"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES!"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\">Abaixo, o time base de futebol do inesquec\u00edvel e super campe\u00e3o AMA (Associa\u00e7\u00e3o Miradourense de Atletismo), entre os anos finais da d\u00e9cada de 1950 e in\u00edcio dos anos 1960.<\/span><\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-neternos-campeoes\/142921632_109730881100536_2613587894959323172_o\/\" rel=\"attachment wp-att-2093\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-2093\" src=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg\" alt=\"\" width=\"790\" height=\"527\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Em p\u00e9, da esquerda para a direita:\u00a0<\/strong>Z\u00c9 AMARAL, BECA, FIRMINO ROCHA, SEBASTI\u00c3O BISPO E TATAIA MOREIRA\u00a0 \/\u00a0\u00a0<strong>Agachados, da esquerda para a direita:<\/strong>\u00a0J\u00c9SUS MOREIRA, CHIC\u00c3O, NILO, FREDERICO, LIQUINHA, DOMINGOS FERRAREZ E T\u00c3OZINHO.<\/span><\/p>\n<p><span style=\"color: #000000;\">Parab\u00e9ns a todos e a todas as desportistas do munic\u00edpio de Miradouro!<\/span><\/p>\n<p><span style=\"color: #000000;\"><em><strong>Fotografia: acervo do Departamento de Museu e Arquivo da Secretaria de Cultura e Turismo de Miradouro \u2013 MG.\u00a0<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abaixo, o time base de futebol do inesquec\u00edvel e super campe\u00e3o AMA (Associa\u00e7\u00e3o Miradourense de Atletismo), entre os anos finais da d\u00e9cada de 1950 e in\u00edcio dos anos 1960. Em p\u00e9, da esquerda para a direita:\u00a0Z\u00c9 AMARAL, BECA, FIRMINO ROCHA, SEBASTI\u00c3O BISPO E TATAIA MOREIRA\u00a0 \/\u00a0\u00a0Agachados, da esquerda para a direita:\u00a0J\u00c9SUS MOREIRA, CHIC\u00c3O, NILO, FREDERICO, LIQUINHA, DOMINGOS FERRAREZ E T\u00c3OZINHO. Parab\u00e9ns a todos e a todas as desportistas do munic\u00edpio de Miradouro! Fotografia: acervo do Departamento de Museu e Arquivo da Secretaria de Cultura e Turismo de Miradouro \u2013 MG.\u00a0<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"categories":[1],"tags":[468,469,289,173],"author_meta":{"display_name":"Portal Miradouro","author_link":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"},"featured_img":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES! - Portal Miradouro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES! - Portal Miradouro\" \/>\n<meta property=\"og:description\" content=\"Abaixo, o time base de futebol do inesquec\u00edvel e super campe\u00e3o AMA (Associa\u00e7\u00e3o Miradourense de Atletismo), entre os anos finais da d\u00e9cada de 1950 e in\u00edcio dos anos 1960. Em p\u00e9, da esquerda para a direita:\u00a0Z\u00c9 AMARAL, BECA, FIRMINO ROCHA, SEBASTI\u00c3O BISPO E TATAIA MOREIRA\u00a0 \/\u00a0\u00a0Agachados, da esquerda para a direita:\u00a0J\u00c9SUS MOREIRA, CHIC\u00c3O, NILO, FREDERICO, LIQUINHA, DOMINGOS FERRAREZ E T\u00c3OZINHO. Parab\u00e9ns a todos e a todas as desportistas do munic\u00edpio de Miradouro! Fotografia: acervo do Departamento de Museu e Arquivo da Secretaria de Cultura e Turismo de Miradouro \u2013 MG.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Miradouro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalmiradouro2020\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-29T20:57:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Miradouro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/\",\"name\":\"Portal Miradouro\",\"description\":\"O seu portal de not\\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg\",\"contentUrl\":\"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#webpage\",\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/\",\"name\":\"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\\u00d5ES! - Portal Miradouro\",\"isPartOf\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#primaryimage\"},\"datePublished\":\"2021-01-29T20:57:32+00:00\",\"dateModified\":\"2021-01-29T20:57:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.portalmiradouro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\\u00d5ES!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6\",\"name\":\"Portal Miradouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g\",\"caption\":\"Portal Miradouro\"},\"sameAs\":[\"http:\/\/www.portalmiradouro.com.br\",\"https:\/\/www.facebook.com\/Portalmiradouro.com.br\",\"https:\/\/www.instagram.com\/portalmiradouro\/\",\"https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/\",\"https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w\"],\"url\":\"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES! - Portal Miradouro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/","og_locale":"pt_BR","og_type":"article","og_title":"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES! - Portal Miradouro","og_description":"Abaixo, o time base de futebol do inesquec\u00edvel e super campe\u00e3o AMA (Associa\u00e7\u00e3o Miradourense de Atletismo), entre os anos finais da d\u00e9cada de 1950 e in\u00edcio dos anos 1960. Em p\u00e9, da esquerda para a direita:\u00a0Z\u00c9 AMARAL, BECA, FIRMINO ROCHA, SEBASTI\u00c3O BISPO E TATAIA MOREIRA\u00a0 \/\u00a0\u00a0Agachados, da esquerda para a direita:\u00a0J\u00c9SUS MOREIRA, CHIC\u00c3O, NILO, FREDERICO, LIQUINHA, DOMINGOS FERRAREZ E T\u00c3OZINHO. Parab\u00e9ns a todos e a todas as desportistas do munic\u00edpio de Miradouro! Fotografia: acervo do Departamento de Museu e Arquivo da Secretaria de Cultura e Turismo de Miradouro \u2013 MG.\u00a0","og_url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/","og_site_name":"Portal Miradouro","article_publisher":"https:\/\/www.facebook.com\/portalmiradouro2020","article_author":"https:\/\/www.facebook.com\/Portalmiradouro.com.br","article_published_time":"2021-01-29T20:57:32+00:00","og_image":[{"url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Portal Miradouro","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website","url":"https:\/\/www.portalmiradouro.com.br\/site\/","name":"Portal Miradouro","description":"O seu portal de not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.portalmiradouro.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg","contentUrl":"http:\/\/www.portalmiradouro.com.br\/site\/wp-content\/uploads\/2021\/01\/142921632_109730881100536_2613587894959323172_o.jpg"},{"@type":"WebPage","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#webpage","url":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/","name":"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES! - Portal Miradouro","isPartOf":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#primaryimage"},"datePublished":"2021-01-29T20:57:32+00:00","dateModified":"2021-01-29T20:57:32+00:00","author":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6"},"breadcrumb":{"@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.portalmiradouro.com.br\/site\/2021\/01\/29\/miradouro-quem-ama-respeita-e-homenageia-seus-eternos-campeoes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.portalmiradouro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"MIRADOURO: QUEM AMA RESPEITA E HOMENAGEIA SEUS ETERNOS CAMPE\u00d5ES!"}]},{"@type":"Person","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#\/schema\/person\/4cc54eb1e2669057670c45f0992e49e6","name":"Portal Miradouro","image":{"@type":"ImageObject","@id":"https:\/\/www.portalmiradouro.com.br\/site\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/183be5e806e4db6ca84a30fef12e1fcb?s=96&d=mm&r=g","caption":"Portal Miradouro"},"sameAs":["http:\/\/www.portalmiradouro.com.br","https:\/\/www.facebook.com\/Portalmiradouro.com.br","https:\/\/www.instagram.com\/portalmiradouro\/","https:\/\/www.linkedin.com\/in\/portal-miradouro-56171b126\/","https:\/\/www.youtube.com\/channel\/UCxin3iT2BCsLZneNCXn2I4w"],"url":"https:\/\/www.portalmiradouro.com.br\/site\/author\/portal\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Destaque<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">ama<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">cultura<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">esporte<\/a>","<a href=\"https:\/\/www.portalmiradouro.com.br\/site\/category\/portal\/\" class=\"advgb-post-tax-term\">Miradouro<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ama<\/span>","<span class=\"advgb-post-tax-term\">cultura<\/span>","<span class=\"advgb-post-tax-term\">esporte<\/span>","<span class=\"advgb-post-tax-term\">Miradouro<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 5 anos ago","modified":"Updated 5 anos ago"},"absolute_dates":{"created":"Posted on 29 de janeiro de 2021","modified":"Updated on 29 de janeiro de 2021"},"absolute_dates_time":{"created":"Posted on 29 de janeiro de 2021 17:57","modified":"Updated on 29 de janeiro de 2021 17:57"},"featured_img_caption":"","_links":{"self":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/2099"}],"collection":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/comments?post=2099"}],"version-history":[{"count":2,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/2099\/revisions"}],"predecessor-version":[{"id":2101,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/posts\/2099\/revisions\/2101"}],"wp:attachment":[{"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/media?parent=2099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/categories?post=2099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalmiradouro.com.br\/site\/wp-json\/wp\/v2\/tags?post=2099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}